{"id":120649,"date":"2026-05-13T23:00:46","date_gmt":"2026-05-13T20:00:46","guid":{"rendered":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/"},"modified":"2026-05-13T23:00:46","modified_gmt":"2026-05-13T20:00:46","slug":"kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi","status":"publish","type":"post","link":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/","title":{"rendered":"Kanada&#8217;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi"},"content":{"rendered":"<p>Kanada&#8217;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi<\/p>\n<p>\u00dc\u00e7\u00fcnc\u00fc y\u0131ll\u0131k \u0130fade \u00d6zg\u00fcrl\u00fc\u011f\u00fc Merkezi toplant\u0131s\u0131 Kanada&#8217;da s\u00fcrg\u00fcn gazeteciler ve medya aktivistlerinin geni\u015f kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti ve uluslararas\u0131 d\u00fczeyde ifade \u00f6zg\u00fcrl\u00fc\u011f\u00fcn\u00fcn durumunu de\u011ferlendirdi.<\/p>\n<p>&#8220;8Sobhan&#8221; haber ajans\u0131na g\u00f6re, bu toplant\u0131 Toronto \u015fehrinde D\u00fcnya Bas\u0131n \u00d6zg\u00fcrl\u00fc\u011f\u00fc G\u00fcn\u00fc vesilesiyle d\u00fczenlendi ve \u00e7e\u015fitli \u00fclkelerden yakla\u015f\u0131k 300 s\u00fcrg\u00fcn gazetecinin kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti.<\/p>\n<p>Haberde ayr\u0131ca, Asya, Avrupa, Orta Do\u011fu, Afrika ve G\u00fcney Amerika dahil olmak \u00fczere d\u00fcnyan\u0131n farkl\u0131 b\u00f6lgelerinden 40&#8217;tan fazla \u00fclkenin gazetecilerinin bu programa kat\u0131ld\u0131\u011f\u0131 belirtiliyor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kanada&#8217;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi \u00dc\u00e7\u00fcnc\u00fc y\u0131ll\u0131k \u0130fade \u00d6zg\u00fcrl\u00fc\u011f\u00fc Merkezi toplant\u0131s\u0131 Kanada&#8217;da s\u00fcrg\u00fcn gazeteciler ve medya aktivistlerinin geni\u015f kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti ve uluslararas\u0131 d\u00fczeyde ifade \u00f6zg\u00fcrl\u00fc\u011f\u00fcn\u00fcn durumunu de\u011ferlendirdi. &#8220;8Sobhan&#8221; haber ajans\u0131na g\u00f6re, bu toplant\u0131 Toronto \u015fehrinde D\u00fcnya Bas\u0131n \u00d6zg\u00fcrl\u00fc\u011f\u00fc G\u00fcn\u00fc vesilesiyle d\u00fczenlendi ve \u00e7e\u015fitli \u00fclkelerden yakla\u015f\u0131k 300 s\u00fcrg\u00fcn gazetecinin kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti. Haberde ayr\u0131ca, &hellip;<\/p>\n","protected":false},"author":1,"featured_media":120648,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[20],"tags":[],"class_list":["post-120649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-world"],"_wp_page_template":null,"_wp_attached_file":null,"_wp_attachment_metadata":null,"_edit_lock":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kanada&#039;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi - ShiaWaves Turkish - \u015eia Haberleri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kanada&#039;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi - ShiaWaves Turkish - \u015eia Haberleri\" \/>\n<meta property=\"og:description\" content=\"Kanada&#8217;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi \u00dc\u00e7\u00fcnc\u00fc y\u0131ll\u0131k \u0130fade \u00d6zg\u00fcrl\u00fc\u011f\u00fc Merkezi toplant\u0131s\u0131 Kanada&#8217;da s\u00fcrg\u00fcn gazeteciler ve medya aktivistlerinin geni\u015f kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti ve uluslararas\u0131 d\u00fczeyde ifade \u00f6zg\u00fcrl\u00fc\u011f\u00fcn\u00fcn durumunu de\u011ferlendirdi. &#8220;8Sobhan&#8221; haber ajans\u0131na g\u00f6re, bu toplant\u0131 Toronto \u015fehrinde D\u00fcnya Bas\u0131n \u00d6zg\u00fcrl\u00fc\u011f\u00fc G\u00fcn\u00fc vesilesiyle d\u00fczenlendi ve \u00e7e\u015fitli \u00fclkelerden yakla\u015f\u0131k 300 s\u00fcrg\u00fcn gazetecinin kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti. Haberde ayr\u0131ca, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/\" \/>\n<meta property=\"og:site_name\" content=\"ShiaWaves Turkish - \u015eia Haberleri\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T20:00:46+00:00\" \/>\n<meta name=\"author\" content=\"modir\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"modir\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/\",\"url\":\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/\",\"name\":\"Kanada'da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi - ShiaWaves Turkish - \u015eia Haberleri\",\"isPartOf\":{\"@id\":\"https:\/\/shiawaves.com\/turkish\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/shiawaves.com\/turkish\/wp-content\/uploads\/sites\/6\/2026\/05\/file_3289.jpg\",\"datePublished\":\"2026-05-13T20:00:46+00:00\",\"dateModified\":\"2026-05-13T20:00:46+00:00\",\"author\":{\"@id\":\"https:\/\/shiawaves.com\/turkish\/#\/schema\/person\/9f68d5023e948086b9348fba5aebd954\"},\"breadcrumb\":{\"@id\":\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#primaryimage\",\"url\":\"https:\/\/shiawaves.com\/turkish\/wp-content\/uploads\/sites\/6\/2026\/05\/file_3289.jpg\",\"contentUrl\":\"https:\/\/shiawaves.com\/turkish\/wp-content\/uploads\/sites\/6\/2026\/05\/file_3289.jpg\",\"width\":1280,\"height\":860},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/shiawaves.com\/turkish\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kanada&#8217;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/shiawaves.com\/turkish\/#website\",\"url\":\"https:\/\/shiawaves.com\/turkish\/\",\"name\":\"ShiaWaves Turkish - \u015eia Haberleri\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/shiawaves.com\/turkish\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/shiawaves.com\/turkish\/#\/schema\/person\/9f68d5023e948086b9348fba5aebd954\",\"name\":\"modir\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\/\/shiawaves.com\/turkish\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8e76f93cdbdd480bd8918d1e0e1d938664c9cb1516c2a57a2b96fe50b507a6b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8e76f93cdbdd480bd8918d1e0e1d938664c9cb1516c2a57a2b96fe50b507a6b9?s=96&d=mm&r=g\",\"caption\":\"modir\"},\"sameAs\":[\"https:\/\/shiawaves.com\"],\"url\":\"https:\/\/shiawaves.com\/turkish\/author\/modir\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kanada'da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi - ShiaWaves Turkish - \u015eia Haberleri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/","og_locale":"tr_TR","og_type":"article","og_title":"Kanada'da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi - ShiaWaves Turkish - \u015eia Haberleri","og_description":"Kanada&#8217;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi \u00dc\u00e7\u00fcnc\u00fc y\u0131ll\u0131k \u0130fade \u00d6zg\u00fcrl\u00fc\u011f\u00fc Merkezi toplant\u0131s\u0131 Kanada&#8217;da s\u00fcrg\u00fcn gazeteciler ve medya aktivistlerinin geni\u015f kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti ve uluslararas\u0131 d\u00fczeyde ifade \u00f6zg\u00fcrl\u00fc\u011f\u00fcn\u00fcn durumunu de\u011ferlendirdi. &#8220;8Sobhan&#8221; haber ajans\u0131na g\u00f6re, bu toplant\u0131 Toronto \u015fehrinde D\u00fcnya Bas\u0131n \u00d6zg\u00fcrl\u00fc\u011f\u00fc G\u00fcn\u00fc vesilesiyle d\u00fczenlendi ve \u00e7e\u015fitli \u00fclkelerden yakla\u015f\u0131k 300 s\u00fcrg\u00fcn gazetecinin kat\u0131l\u0131m\u0131yla ger\u00e7ekle\u015fti. Haberde ayr\u0131ca, &hellip;","og_url":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/","og_site_name":"ShiaWaves Turkish - \u015eia Haberleri","article_published_time":"2026-05-13T20:00:46+00:00","author":"modir","twitter_card":"summary_large_image","twitter_misc":{"Yazan:":"modir","Tahmini okuma s\u00fcresi":"1 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/","url":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/","name":"Kanada'da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi - ShiaWaves Turkish - \u015eia Haberleri","isPartOf":{"@id":"https:\/\/shiawaves.com\/turkish\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#primaryimage"},"image":{"@id":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#primaryimage"},"thumbnailUrl":"https:\/\/shiawaves.com\/turkish\/wp-content\/uploads\/sites\/6\/2026\/05\/file_3289.jpg","datePublished":"2026-05-13T20:00:46+00:00","dateModified":"2026-05-13T20:00:46+00:00","author":{"@id":"https:\/\/shiawaves.com\/turkish\/#\/schema\/person\/9f68d5023e948086b9348fba5aebd954"},"breadcrumb":{"@id":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#primaryimage","url":"https:\/\/shiawaves.com\/turkish\/wp-content\/uploads\/sites\/6\/2026\/05\/file_3289.jpg","contentUrl":"https:\/\/shiawaves.com\/turkish\/wp-content\/uploads\/sites\/6\/2026\/05\/file_3289.jpg","width":1280,"height":860},{"@type":"BreadcrumbList","@id":"https:\/\/shiawaves.com\/turkish\/2026\/05\/13\/kanadada-surgundeki-gazetecilerin-dunya-zirvesi-ozgurluk-temali-duzenlendi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shiawaves.com\/turkish\/"},{"@type":"ListItem","position":2,"name":"Kanada&#8217;da S\u00fcrg\u00fcndeki Gazetecilerin D\u00fcnya Zirvesi \u00d6zg\u00fcrl\u00fck Temal\u0131 D\u00fczenlendi"}]},{"@type":"WebSite","@id":"https:\/\/shiawaves.com\/turkish\/#website","url":"https:\/\/shiawaves.com\/turkish\/","name":"ShiaWaves Turkish - \u015eia Haberleri","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shiawaves.com\/turkish\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Person","@id":"https:\/\/shiawaves.com\/turkish\/#\/schema\/person\/9f68d5023e948086b9348fba5aebd954","name":"modir","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/shiawaves.com\/turkish\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8e76f93cdbdd480bd8918d1e0e1d938664c9cb1516c2a57a2b96fe50b507a6b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8e76f93cdbdd480bd8918d1e0e1d938664c9cb1516c2a57a2b96fe50b507a6b9?s=96&d=mm&r=g","caption":"modir"},"sameAs":["https:\/\/shiawaves.com"],"url":"https:\/\/shiawaves.com\/turkish\/author\/modir\/"}]}},"_links":{"self":[{"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/posts\/120649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/comments?post=120649"}],"version-history":[{"count":0,"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/posts\/120649\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/media\/120648"}],"wp:attachment":[{"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/media?parent=120649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/categories?post=120649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shiawaves.com\/turkish\/wp-json\/wp\/v2\/tags?post=120649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}