{"id":12007,"count":1,"description":"","link":"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/","name":"Second-Term Presidency","slug":"second-term-presidency","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Second-Term Presidency Archives - Shia Waves<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Second-Term Presidency Archives - Shia Waves\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/\" \/>\n<meta property=\"og:site_name\" content=\"Shia Waves\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/tag\\\/second-term-presidency\\\/\",\"url\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/tag\\\/second-term-presidency\\\/\",\"name\":\"Second-Term Presidency Archives - Shia Waves\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/tag\\\/second-term-presidency\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/tag\\\/second-term-presidency\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Second-Term Presidency\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/#website\",\"url\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/\",\"name\":\"Shia Waves\",\"description\":\"Just another ShiaWaves site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shiawaves.com\\\/english\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Second-Term Presidency Archives - Shia Waves","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/","og_locale":"en_US","og_type":"article","og_title":"Second-Term Presidency Archives - Shia Waves","og_url":"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/","og_site_name":"Shia Waves","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/","url":"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/","name":"Second-Term Presidency Archives - Shia Waves","isPartOf":{"@id":"https:\/\/shiawaves.com\/english\/#website"},"breadcrumb":{"@id":"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/shiawaves.com\/english\/tag\/second-term-presidency\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shiawaves.com\/english\/"},{"@type":"ListItem","position":2,"name":"Second-Term Presidency"}]},{"@type":"WebSite","@id":"https:\/\/shiawaves.com\/english\/#website","url":"https:\/\/shiawaves.com\/english\/","name":"Shia Waves","description":"Just another ShiaWaves site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shiawaves.com\/english\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/shiawaves.com\/english\/wp-json\/wp\/v2\/tags\/12007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shiawaves.com\/english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/shiawaves.com\/english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/shiawaves.com\/english\/wp-json\/wp\/v2\/posts?tags=12007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}